{"id":10381,"date":"2017-10-13T11:55:29","date_gmt":"2017-10-13T11:55:29","guid":{"rendered":"https:\/\/seifid.vdisain.dev\/?product=kasutatud-tulekindel-dokumendiseif-secureline-sdo-170k-nt-fire-017-120-paper"},"modified":"2020-04-23T18:15:54","modified_gmt":"2020-04-23T18:15:54","slug":"kasutatud-tulekindel-dokumendiseif-secureline-sdo-170k-nt-fire-017-120-paper","status":"publish","type":"product","link":"https:\/\/dev.seifid.ee\/en\/product\/kasutatud-tulekindel-dokumendiseif-secureline-sdo-170k-nt-fire-017-120-paper\/","title":{"rendered":"Kasutatud tulekindel dokumendiseif SecureLine SDO 170K NT Fire 017-120 Paper"},"content":{"rendered":"<p>Mudel: SecureLine SDO 170K<br \/>\nTulekindlus: NT Fire 017-120 Paper<br \/>\nTurvaklass: puudub<br \/>\nV\u00e4lism\u00f5\u00f5t: kxlxs 1615x800x635+ k\u00e4epide 40mm<br \/>\nSisem\u00f5\u00f5t: kxlxs 1440x630x420mm<br \/>\nLukustus: v\u00f5tmelukk Eagle- 2 v\u00f5tit<br \/>\nRiiul: 3tk<br \/>\nKaal: u 450 kg<br \/>\nMaht:\u00a0 381 liitrit<br \/>\nAnkurdusvalmidus: puudub<br \/>\nV\u00e4rv: RAL 9002 hall<br \/>\nTootmisaasta: 2004<\/p>","protected":false},"excerpt":{"rendered":"<p>Mudel: SecureLine SDO 170K Tulekindlus: NT Fire 017-120 Paper Turvaklass: puudub V\u00e4lism\u00f5\u00f5t: kxlxs 1615x800x635+ k\u00e4epide 40mm Sisem\u00f5\u00f5t: kxlxs 1440x630x420mm Lukustus:<\/p>","protected":false},"featured_media":10382,"template":"","meta":[],"product_brand":[],"product_cat":[401],"product_tag":[],"class_list":{"0":"post-10381","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-kasutatud-seifid","7":"pa_kaal-kg-1211","8":"pa_lukutuup-keylock-eagle","9":"pa_maht-l-1841","10":"pa_sisemised-moot-1440x630x420","11":"pa_valised-mootme-1615x800x635","12":"pa_varvus-ral-9002","14":"first","15":"instock","16":"shipping-taxable","17":"purchasable","18":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/product\/10381","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/product\/10381\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/media\/10382"}],"wp:attachment":[{"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/media?parent=10381"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/product_brand?post=10381"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/product_cat?post=10381"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/product_tag?post=10381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}