{"id":10573,"date":"2020-01-06T16:53:50","date_gmt":"2020-01-06T16:53:50","guid":{"rendered":"https:\/\/seifid.vdisain.dev\/?product=turvakapp-griffon-m-20-e"},"modified":"2021-09-24T15:18:49","modified_gmt":"2021-09-24T15:18:49","slug":"turvakapp-griffon-m-20-e","status":"publish","type":"product","link":"https:\/\/dev.seifid.ee\/en\/product\/turvakapp-griffon-m-20-e\/","title":{"rendered":"Turvakapp Griffon M.20.E"},"content":{"rendered":"<p>Elektrooniline koodlukk M LocksVdS Class 2 EN 1300<\/p>","protected":false},"excerpt":{"rendered":"<p>Elektrooniline koodlukk M LocksVdS Class 2 EN 1300<\/p>","protected":false},"featured_media":10574,"template":"","meta":[],"product_brand":[],"product_cat":[428],"product_tag":[],"class_list":{"0":"post-10573","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-turvakapp-me-seeria","7":"pa_kaal-kg-1071","8":"pa_lukutuup-safe-electronic-code-lock-m-locks-the-netherlands-vds-class-2-with-delay-opening-function","9":"pa_maht-l-1065","10":"pa_murdvarguseklass-en14450-s1","11":"pa_sisemised-moot-196x417x290","12":"pa_valised-mootme-200x425x345","13":"pa_varvus-grey-ral-7040-ral-7035","15":"first","16":"instock","17":"shipping-taxable","18":"purchasable","19":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/product\/10573","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/product\/10573\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/media\/10574"}],"wp:attachment":[{"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/media?parent=10573"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/product_brand?post=10573"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/product_cat?post=10573"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.seifid.ee\/en\/wp-json\/wp\/v2\/product_tag?post=10573"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}