{"id":10505,"date":"2018-11-14T23:51:25","date_gmt":"2018-11-14T23:51:25","guid":{"rendered":"https:\/\/seifid.vdisain.dev\/?product=masterlock-ml-5428-eurd"},"modified":"2019-11-12T15:56:44","modified_gmt":"2019-11-12T15:56:44","slug":"masterlock-ml-5428-eurd","status":"publish","type":"product","link":"https:\/\/dev.seifid.ee\/fi\/tuote\/masterlock-ml-5428-eurd\/","title":{"rendered":"Masterlock ML 5428 EURD"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":10506,"template":"","meta":[],"product_brand":[],"product_cat":[227],"product_tag":[],"class_list":{"0":"post-10505","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-masterlock-votmeseifid","7":"pa_kaal-kg-3-kg","8":"pa_sisemised-moot-korgusxlaiusxsugavus-66-x-97-x-22","9":"pa_valised-mootme-korgusxlaiusxsugavus-124-x-178-x-133","11":"first","12":"instock","13":"shipping-taxable","14":"purchasable","15":"product-type-simple"},"_links":{"self":[{"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/product\/10505","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":0,"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/product\/10505\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/media\/10506"}],"wp:attachment":[{"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/media?parent=10505"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/product_brand?post=10505"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/product_cat?post=10505"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/product_tag?post=10505"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}