{"id":270,"count":9,"description":"Murdvarguse vastane kaitse- \"Grade\" 0\u00a0EN 1143-1 (turvaklass 0)\r\n\tTulekindluse kaitse- klass\u00a0EN 1047-1 S60P\u00a0(60 minutit)\r\n\tStandardvarustuses kahepoolne v\u00f5tmelukk (2v\u00f5tit)\u00a0v\u00f5i lisavarustusena elektrooniline\u00a0koodlukk: hind\u00a0175.- +km\u200b\r\n\tAnkurdamisvalmidus p\u00f5randa k\u00fclge\r\n\tV\u00e4rvus - hall RAL7035","link":"https:\/\/dev.seifid.ee\/fi\/tuote-osasto\/rahaseifid1657879811\/koln-murdvarguseklassiga-seifid\/","name":"KOLN murdvarguseklassiga seifid","slug":"koln-murdvarguseklassiga-seifid","taxonomy":"product_cat","parent":220,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/product_cat\/270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/product_cat\/220"}],"wp:post_type":[{"href":"https:\/\/dev.seifid.ee\/fi\/wp-json\/wp\/v2\/product?product_cat=270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}