{"id":284,"count":9,"description":"Murdvargakindel - klass 0 EN 1143-1\r\n\tTulekindel - klass DIN 1047-1 S60P\r\n\tKahepoolne v\u00f5tmelukk (kaasas 2 v\u00f5tit)\r\n\tAnkurdamisvalmidus p\u00f5randa k\u00fclge\r\n\tV\u00e4rvus hall, RAL 7035","link":"https:\/\/dev.seifid.ee\/ru\/product-category\/tulekindlad-seifid\/tulekindlad-seifid-koln-klass-0\/","name":"Tulekindlad seifid K\u00f6ln (KLASS 0)","slug":"tulekindlad-seifid-koln-klass-0","taxonomy":"product_cat","parent":282,"meta":[],"menu_order":0,"_links":{"self":[{"href":"https:\/\/dev.seifid.ee\/ru\/wp-json\/wp\/v2\/product_cat\/284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dev.seifid.ee\/ru\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/dev.seifid.ee\/ru\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/dev.seifid.ee\/ru\/wp-json\/wp\/v2\/product_cat\/282"}],"wp:post_type":[{"href":"https:\/\/dev.seifid.ee\/ru\/wp-json\/wp\/v2\/product?product_cat=284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}